{"id":392,"date":"2021-05-27T10:00:00","date_gmt":"2021-05-27T08:00:00","guid":{"rendered":"https:\/\/www.gadisa.es\/blog\/?p=272"},"modified":"2021-05-27T10:00:00","modified_gmt":"2021-05-27T08:00:00","slug":"guia-de-reciclaje-para-ninos","status":"publish","type":"post","link":"https:\/\/www.gadisaretail.es\/blog\/guia-de-reciclaje-para-ninos\/","title":{"rendered":"Gu\u00eda de reciclaje para ni\u00f1os"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El reciclaje no solo es una tarea para los adultos. Los ni\u00f1os tambi\u00e9n deben aprender a reciclar para ser conscientes ya a edades tempranas de la importancia en el cuidado del medio ambiente y de su entorno. Padres y profesores deben preparar para ellos una peque\u00f1a <strong>gu\u00eda de reciclaje para ni\u00f1os <\/strong>con la que puedan aprender algunas acciones para reciclar.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">En la actualidad, existen multitud de <strong>juegos y actividades relacionadas con el reciclaje<\/strong>. Todas ellas est\u00e1n pensadas para ense\u00f1ar a los ni\u00f1os a reciclar. As\u00ed podr\u00e1n aprender a generar menos basura, a separar residuos y a reutilizar todo aquello que les pueda volver a ser \u00fatil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por qu\u00e9 es importante reciclar para ni\u00f1os<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La importancia del reciclaje, tanto para adultos como para ni\u00f1os, es la misma. El objetivo es poder aprovechar los materiales usados para crear con ellos nuevos objetos. De esta forma, se consigue tambi\u00e9n cuidar del entorno y el medio ambiente. Es la primera tarea que deber\u00e1 tener en cuenta nuestra <strong>gu\u00eda de reciclaje para ni\u00f1os<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de los 3 a\u00f1os, los ni\u00f1os ya pueden ir <strong>aprendiendo a reciclar<\/strong>. Empezar tan pronto supone que tomen conciencia de que su aportaci\u00f3n ayuda a salvar el planeta. Aprender cu\u00e1les son los materiales que deben reciclar les permitir\u00e1 conocer los productos que deben usar y aquellos que deben separar para el proceso de reciclaje. Aqu\u00ed te contamos <a href=\"https:\/\/www.gadisaretail.es\/blog\/que-es-reciclar-explicacion-para-ninos\/\" target=\"_blank\" rel=\"noreferrer noopener\">c\u00f3mo explicarles bien qu\u00e9 es el reciclaje<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si desde bien pronto los ni\u00f1os toman conciencia de la <strong>importancia de reciclar<\/strong>, lo har\u00e1n durante el resto de sus vidas. Tomar\u00e1n las tareas de reciclaje como algo cotidiano y disfrutar\u00e1n de h\u00e1bitos saludables. Porque, adem\u00e1s de cuidar del medio ambiente, reciclar tambi\u00e9n supone llevar en casa una vida m\u00e1s sana.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.gadisaretail.es\/blog\/wp-content\/uploads\/2021\/06\/Por-que-es-importante-reciclar-para-ninos.jpg\" alt=\"Por qu\u00e9 es importante reciclar para ni\u00f1os\" class=\"wp-image-274\"\/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Gu\u00eda de reciclaje para ni\u00f1os que empiezan a reciclar<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una peque\u00f1a <strong>gu\u00eda de reciclaje para ni\u00f1os <\/strong>es la mejor manera para que empiecen a reciclar. Adem\u00e1s de los juegos y actividades que se puedan llevar a cabo, es muy importante partir de una base concreta. Hay una f\u00f3rmula gen\u00e9rica que emplea con los m\u00e1s peque\u00f1os y es explicarles lo que son las tres R: reutilizar, reciclar y reducir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primero de los conceptos consiste en la importancia de <strong>reutilizar diversos objetos para darles otros usos<\/strong>. \u00bfPor qu\u00e9 tirar sin m\u00e1s todo aquello que parece que no nos sirve? A los ni\u00f1os se les puede ense\u00f1ar a reutilizar algunas de sus cosas. Esto no solo les valdr\u00e1 para aprender a reciclar, sino tambi\u00e9n para fomentar su creatividad e imaginaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El reciclaje es la manera de ense\u00f1arles <strong>c\u00f3mo deben reciclar<\/strong>. Es un buen momento aqu\u00ed para proyectar juegos, actividades e incluso manualidades en las que aprendan a reciclar. \u00bfPara qu\u00e9 sirven, por ejemplo, los contenedores de colores que ven por las calles?, \u00bfsaben cu\u00e1les son los materiales que deben arrojar en cada uno de ellos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, el concepto de reducir. Es muy importante que los ni\u00f1os aprendan a <strong>reducir la cantidad de basura que se genera cada d\u00eda<\/strong>. Pero, al mismo tiempo, es necesario que sepan que tambi\u00e9n deben reducir en casa el consumo de agua, de energ\u00eda, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una sencilla <strong>gu\u00eda de reciclaje para ni\u00f1os<\/strong> es fundamental para que los m\u00e1s peque\u00f1os tomen conciencia de la sostenibilidad. Un concepto con el que deben familiarizarse bien pronto y llevarlo a sus vidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reciclaje no solo es una tarea para los adultos. Los ni\u00f1os tambi\u00e9n deben aprender a reciclar para ser conscientes ya a edades tempranas de la importancia en el cuidado del medio ambiente y de su entorno. Padres y profesores deben preparar para ellos una peque\u00f1a gu\u00eda de reciclaje para ni\u00f1os con la que puedan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mejor-cadena-de-supermercados"],"_links":{"self":[{"href":"https:\/\/www.gadisaretail.es\/blog\/wp-json\/wp\/v2\/posts\/392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gadisaretail.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gadisaretail.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gadisaretail.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gadisaretail.es\/blog\/wp-json\/wp\/v2\/comments?post=392"}],"version-history":[{"count":0,"href":"https:\/\/www.gadisaretail.es\/blog\/wp-json\/wp\/v2\/posts\/392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gadisaretail.es\/blog\/wp-json\/wp\/v2\/media\/1873"}],"wp:attachment":[{"href":"https:\/\/www.gadisaretail.es\/blog\/wp-json\/wp\/v2\/media?parent=392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gadisaretail.es\/blog\/wp-json\/wp\/v2\/categories?post=392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gadisaretail.es\/blog\/wp-json\/wp\/v2\/tags?post=392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}